{"id":2596,"date":"2016-03-23T17:38:31","date_gmt":"2016-03-23T16:38:31","guid":{"rendered":"http:\/\/www.hotel-royal-antibes.com\/es\/galerie\/"},"modified":"2023-12-02T13:35:51","modified_gmt":"2023-12-02T12:35:51","slug":"galeria","status":"publish","type":"page","link":"https:\/\/www.hotel-royal-antibes.com\/es\/galeria\/","title":{"rendered":"Galeria"},"content":{"rendered":"<p>[vc_row][vc_column][vc_masonry_media_grid initial_loading_animation=\u00bbfadeIn\u00bb grid_id=\u00bbvc_gid:1701520314723-9438b18c-efe6-2&#8243; include=\u00bb900,4257,872,4259,892,898,894,862,4244,7853,8123,8079,7858,8084,8054,880,8069,896,4258,916,884,7838,7843,7777,858,842,8128,816,8064,8059,4255,818,1048,830,832,834,804,798,796,1042,1046,1050,1052,1054,792,1040,1038,1036,1034,1032,1030,1026,1024,1022,1019,962,1015,621,920,918,888,4243,7848&#8243;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_masonry_media_grid initial_loading_animation=\u00bbfadeIn\u00bb grid_id=\u00bbvc_gid:1701520314723-9438b18c-efe6-2&#8243; include=\u00bb900,4257,872,4259,892,898,894,862,4244,7853,8123,8079,7858,8084,8054,880,8069,896,4258,916,884,7838,7843,7777,858,842,8128,816,8064,8059,4255,818,1048,830,832,834,804,798,796,1042,1046,1050,1052,1054,792,1040,1038,1036,1034,1032,1030,1026,1024,1022,1019,962,1015,621,920,918,888,4243,7848&#8243;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2596","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Galer\u00eda de fotos de nuestro hotel de lujo en Antibes con vistas al mar<\/title>\n<meta name=\"description\" content=\"Galer\u00eda de fotos de nuestro hotel de lujo en Antibes con terraza con vistas al mar. Foto de calidad HD de Antibes, la playa privada, el restaurante y el caf\u00e9 Royal, la habitaci\u00f3n con aire acondicionado, amplios apartamentos de lujo y la suite real.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hotel-royal-antibes.com\/es\/galeria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Galer\u00eda de fotos de nuestro hotel de lujo en Antibes con vistas al mar\" \/>\n<meta property=\"og:description\" content=\"Galer\u00eda de fotos de nuestro hotel de lujo en Antibes con terraza con vistas al mar. Foto de calidad HD de Antibes, la playa privada, el restaurante y el caf\u00e9 Royal, la habitaci\u00f3n con aire acondicionado, amplios apartamentos de lujo y la suite real.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hotel-royal-antibes.com\/es\/galeria\/\" \/>\n<meta property=\"og:site_name\" content=\"Royal Antibes\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-02T12:35:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hotel-royal-antibes.com\\\/es\\\/galeria\\\/\",\"url\":\"https:\\\/\\\/www.hotel-royal-antibes.com\\\/es\\\/galeria\\\/\",\"name\":\"Galer\u00eda de fotos de nuestro hotel de lujo en Antibes con vistas al mar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hotel-royal-antibes.com\\\/es\\\/#website\"},\"datePublished\":\"2016-03-23T16:38:31+00:00\",\"dateModified\":\"2023-12-02T12:35:51+00:00\",\"description\":\"Galer\u00eda de fotos de nuestro hotel de lujo en Antibes con terraza con vistas al mar. Foto de calidad HD de Antibes, la playa privada, el restaurante y el caf\u00e9 Royal, la habitaci\u00f3n con aire acondicionado, amplios apartamentos de lujo y la suite real.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hotel-royal-antibes.com\\\/es\\\/galeria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hotel-royal-antibes.com\\\/es\\\/galeria\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hotel-royal-antibes.com\\\/es\\\/galeria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hotel Royal Antibes\",\"item\":\"https:\\\/\\\/www.hotel-royal-antibes.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Galeria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hotel-royal-antibes.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.hotel-royal-antibes.com\\\/es\\\/\",\"name\":\"Royal Antibes\",\"description\":\"Luxury hotel in Antibes on French Riviera\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hotel-royal-antibes.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Galer\u00eda de fotos de nuestro hotel de lujo en Antibes con vistas al mar","description":"Galer\u00eda de fotos de nuestro hotel de lujo en Antibes con terraza con vistas al mar. Foto de calidad HD de Antibes, la playa privada, el restaurante y el caf\u00e9 Royal, la habitaci\u00f3n con aire acondicionado, amplios apartamentos de lujo y la suite real.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hotel-royal-antibes.com\/es\/galeria\/","og_locale":"es_ES","og_type":"article","og_title":"Galer\u00eda de fotos de nuestro hotel de lujo en Antibes con vistas al mar","og_description":"Galer\u00eda de fotos de nuestro hotel de lujo en Antibes con terraza con vistas al mar. Foto de calidad HD de Antibes, la playa privada, el restaurante y el caf\u00e9 Royal, la habitaci\u00f3n con aire acondicionado, amplios apartamentos de lujo y la suite real.","og_url":"https:\/\/www.hotel-royal-antibes.com\/es\/galeria\/","og_site_name":"Royal Antibes","article_modified_time":"2023-12-02T12:35:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hotel-royal-antibes.com\/es\/galeria\/","url":"https:\/\/www.hotel-royal-antibes.com\/es\/galeria\/","name":"Galer\u00eda de fotos de nuestro hotel de lujo en Antibes con vistas al mar","isPartOf":{"@id":"https:\/\/www.hotel-royal-antibes.com\/es\/#website"},"datePublished":"2016-03-23T16:38:31+00:00","dateModified":"2023-12-02T12:35:51+00:00","description":"Galer\u00eda de fotos de nuestro hotel de lujo en Antibes con terraza con vistas al mar. Foto de calidad HD de Antibes, la playa privada, el restaurante y el caf\u00e9 Royal, la habitaci\u00f3n con aire acondicionado, amplios apartamentos de lujo y la suite real.","breadcrumb":{"@id":"https:\/\/www.hotel-royal-antibes.com\/es\/galeria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hotel-royal-antibes.com\/es\/galeria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hotel-royal-antibes.com\/es\/galeria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hotel Royal Antibes","item":"https:\/\/www.hotel-royal-antibes.com\/es\/"},{"@type":"ListItem","position":2,"name":"Galeria"}]},{"@type":"WebSite","@id":"https:\/\/www.hotel-royal-antibes.com\/es\/#website","url":"https:\/\/www.hotel-royal-antibes.com\/es\/","name":"Royal Antibes","description":"Luxury hotel in Antibes on French Riviera","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hotel-royal-antibes.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.hotel-royal-antibes.com\/es\/wp-json\/wp\/v2\/pages\/2596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hotel-royal-antibes.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hotel-royal-antibes.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hotel-royal-antibes.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hotel-royal-antibes.com\/es\/wp-json\/wp\/v2\/comments?post=2596"}],"version-history":[{"count":8,"href":"https:\/\/www.hotel-royal-antibes.com\/es\/wp-json\/wp\/v2\/pages\/2596\/revisions"}],"predecessor-version":[{"id":8133,"href":"https:\/\/www.hotel-royal-antibes.com\/es\/wp-json\/wp\/v2\/pages\/2596\/revisions\/8133"}],"wp:attachment":[{"href":"https:\/\/www.hotel-royal-antibes.com\/es\/wp-json\/wp\/v2\/media?parent=2596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}